{"id":2394,"date":"2017-12-19T12:31:18","date_gmt":"2017-12-19T10:31:18","guid":{"rendered":"http:\/\/lama.es\/?p=2394"},"modified":"2017-12-19T12:31:18","modified_gmt":"2017-12-19T10:31:18","slug":"nouvelle-couvercle-pour-la-vanne-globo","status":"publish","type":"post","link":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/","title":{"rendered":"Nouveau couvercle de polyamide pour la vanne Globo"},"content":{"rendered":"<p>Am\u00e9lioration pour les vannes Globo met\u00e1lliques: nouveau couvercle de polyamide.<\/p>\n<p>L&rsquo;\u00e9quipe d&rsquo;ing\u00e9nierie de Lama a cr\u00e9\u00e9 un nouveau couvercle pour les vannes Globo 4&Prime; (quatre pouces), dans sa version m\u00e9tallique. Ce nouvel dispositif qui a un nouveau moule, est fabriqu\u00e9 dans polyamide charg\u00e9 de fibre de verre. Avec cela nous obtenons que le co\u00fbt de production soit plus \u00e9conomique et par cons\u00e9quent le prix pour le client. Comme le mat\u00e9riel du couvercle est un plus l\u00e9ger, le poids du dispositif diminue aussi.<\/p>\n<p>Dans sa morphologie nous pouvons trouver un nombre \u00e9lev\u00e9 de nerfs, dessin\u00e9s pour le couvercle ait une \u00e9norme r\u00e9sistance devant des changements de pressions, en emp\u00eachant qui se produisent des d\u00e9formations. Tout cela cause d\u2019augmentation de sa durabilit\u00e9.<\/p>\n<p>C&rsquo;est la premi\u00e8re \u00e9tape pour approprier toute la vanne Globo au mat\u00e9riel de polyamide, aussi comme le processus qui s&rsquo;est initi\u00e9 il y a quelques ann\u00e9es pour changer la vanne Globo de 3 \u00a0\u00bb (trois pouces) dans l&rsquo;actuel Globo Plastic.<\/p>\n<p>La pr\u00e9tention de Lama avec ces am\u00e9liorations est d&rsquo;adapter tous nos produits \u00e0 toutes les demandes du march\u00e9, en pensant principalement \u00e0 l&rsquo;eau de mer.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.lama.es\">www.lama.es<\/a><\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_2378\" style=\"width: 246px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2378\" class=\"size-medium wp-image-2378\" src=\"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-disc-Automaster-236x300.jpg\" alt=\"Lama-disc-Automaster\" width=\"236\" height=\"300\" srcset=\"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-disc-Automaster-236x300.jpg 236w, https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-disc-Automaster-806x1024.jpg 806w, https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-disc-Automaster-700x889.jpg 700w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><p id=\"caption-attachment-2378\" class=\"wp-caption-text\">Premi\u00e8re station avec le nouveau couvercle de la vanne de 4&Prime;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9lioration pour les vannes Globo met\u00e1lliques: nouveau couvercle de polyamide. L&rsquo;\u00e9quipe d&rsquo;ing\u00e9nierie de Lama a cr\u00e9\u00e9 un nouveau couvercle pour les vannes Globo 4&Prime; (quatre pouces), dans sa version m\u00e9tallique. Ce nouvel dispositif qui a un nouveau moule, est fabriqu\u00e9 dans polyamide charg\u00e9 de fibre&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-2394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tous"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouveau couvercle de polyamide pour las vannes Globo<\/title>\n<meta name=\"description\" content=\"L&#039;\u00e9quipe d&#039;ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4&quot;, fait en polyamide. C&#039;est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouveau couvercle de polyamide pour las vannes Globo\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00e9quipe d&#039;ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4&quot;, fait en polyamide. C&#039;est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/\" \/>\n<meta property=\"og:site_name\" content=\"LAMA Sistema de Filtrado\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-19T10:31:18+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve-1024x669.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/\"},\"author\":{\"name\":\"Lama\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\"},\"headline\":\"Nouveau couvercle de polyamide pour la vanne Globo\",\"datePublished\":\"2017-12-19T10:31:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/\"},\"wordCount\":230,\"image\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Lama-Globo-Valve.jpg\",\"articleSection\":[\"Tous\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/\",\"url\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/\",\"name\":\"Nouveau couvercle de polyamide pour las vannes Globo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Lama-Globo-Valve.jpg\",\"datePublished\":\"2017-12-19T10:31:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\"},\"description\":\"L'\u00e9quipe d'ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4\\\", fait en polyamide. C'est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Lama-Globo-Valve.jpg\",\"contentUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Lama-Globo-Valve.jpg\",\"width\":3648,\"height\":2382,\"caption\":\"Lama-Globo-Valve\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/nouvelle-couvercle-pour-la-vanne-globo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lama.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouveau couvercle de polyamide pour la vanne Globo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lama.es\\\/fr\\\/\",\"name\":\"LAMA Sistema de Filtrado\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lama.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\",\"name\":\"Lama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"caption\":\"Lama\"},\"sameAs\":[\"https:\\\/\\\/www.lama.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouveau couvercle de polyamide pour las vannes Globo","description":"L'\u00e9quipe d'ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4\", fait en polyamide. C'est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouveau couvercle de polyamide pour las vannes Globo","og_description":"L'\u00e9quipe d'ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4\", fait en polyamide. C'est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide","og_url":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/","og_site_name":"LAMA Sistema de Filtrado","article_published_time":"2017-12-19T10:31:18+00:00","og_image":[{"width":1024,"height":669,"url":"http:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve-1024x669.jpg","type":"image\/jpeg"}],"author":"Lama","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lama","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#article","isPartOf":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/"},"author":{"name":"Lama","@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638"},"headline":"Nouveau couvercle de polyamide pour la vanne Globo","datePublished":"2017-12-19T10:31:18+00:00","mainEntityOfPage":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/"},"wordCount":230,"image":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#primaryimage"},"thumbnailUrl":"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve.jpg","articleSection":["Tous"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/","url":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/","name":"Nouveau couvercle de polyamide pour las vannes Globo","isPartOf":{"@id":"https:\/\/lama.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#primaryimage"},"image":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#primaryimage"},"thumbnailUrl":"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve.jpg","datePublished":"2017-12-19T10:31:18+00:00","author":{"@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638"},"description":"L'\u00e9quipe d'ing\u00e9nierie de Lama a cr\u00e9\u00e9 un couvercle pour les vannes Globo 4\", fait en polyamide. C'est la premi\u00e8re \u00e9tape pour approprier la vanne en polyamide","breadcrumb":{"@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#primaryimage","url":"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve.jpg","contentUrl":"https:\/\/lama.es\/wp-content\/uploads\/2017\/12\/Lama-Globo-Valve.jpg","width":3648,"height":2382,"caption":"Lama-Globo-Valve"},{"@type":"BreadcrumbList","@id":"https:\/\/lama.es\/fr\/nouvelle-couvercle-pour-la-vanne-globo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lama.es\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouveau couvercle de polyamide pour la vanne Globo"}]},{"@type":"WebSite","@id":"https:\/\/lama.es\/fr\/#website","url":"https:\/\/lama.es\/fr\/","name":"LAMA Sistema de Filtrado","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lama.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638","name":"Lama","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","caption":"Lama"},"sameAs":["https:\/\/www.lama.es"]}]}},"_links":{"self":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/2394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/comments?post=2394"}],"version-history":[{"count":7,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/2394\/revisions"}],"predecessor-version":[{"id":2401,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/2394\/revisions\/2401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/media\/2377"}],"wp:attachment":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/media?parent=2394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/categories?post=2394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/tags?post=2394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}