{"id":4325,"date":"2021-03-29T14:24:59","date_gmt":"2021-03-29T12:24:59","guid":{"rendered":"http:\/\/lama.es\/?p=4325"},"modified":"2021-03-29T14:25:33","modified_gmt":"2021-03-29T12:25:33","slug":"les-codes-qr-comme-engagement-pour-loptimisation-des-ressources","status":"publish","type":"post","link":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/","title":{"rendered":"LES CODES QR COMME ENGAGEMENT POUR L&rsquo;OPTIMISATION DES RESSOURCES"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Lama est une organization engag\u00e9e en faveur de l&rsquo;environnement et de l&rsquo;optimisation des ressources naturelles. Par cons\u00e9quent, <strong>nous avons suivi les exigences requises par le march\u00e9 actuel et nous\u00a0 r\u00e9pondons aux indications g\u00e9n\u00e9rales de la pand\u00e9mie<\/strong> ; tous nos produits portent les indications et les instructions sous forme d\u2019un code QR.<\/p>\n<p>Les codes QR font r\u00e9f\u00e9rence aux termes anglais \u201cquick response\u201d, qui se traduisent par une r\u00e9ponse rapide \u00e0 la demande d&rsquo;un produit ou d&rsquo;un service.Dans notre cas, nous avons \u00e9galement ajout\u00e9 cette r\u00e9activit\u00e9 quant aux informations essentielles de chaque produit. De cette mani\u00e8re, sur notre site web <a href=\"https:\/\/www.lama.es\/\">www.lama.es<\/a>, le client final aura acc\u00e8s \u00e0 la page de chacun de nos articles. Gr\u00e2ce au code QR personnalis\u00e9 et \u00e0 sa capacit\u00e9 de synth\u00e8se des donn\u00e9es, l&rsquo;utilisateur pourra acc\u00e9der de mani\u00e8re simple et agile aux contenus suivants:<\/p>\n<p>&#8211; <strong>Caract\u00e9ristiques<\/strong> principales.<\/p>\n<p>&#8211; <strong>Fiche technique<\/strong> t\u00e9l\u00e9chargeable.<\/p>\n<p>&#8211; <strong>Manuel d&rsquo;utilisateur<\/strong> t\u00e9l\u00e9chargeable.<\/p>\n<p>&#8211; <strong>Vid\u00e9o de montage et de d\u00e9montage<\/strong>.<\/p>\n<p>&#8211; <strong>Images<\/strong> correspondant \u00e0 ces produits.<\/p>\n<p>Gr\u00e2ce \u00e0 cela, nous nous assurons que le client est toujours \u00e0 jour concernant les informations dont il a besoin pour obtenir un bon fonctionnement de son filtre, de sa vanne ou de son programmateur.Par exemple, vous ne devrez plus r\u00e9imprimer le manuel d&rsquo;utilisateur de votre filtre \u00e0 chaque mise \u00e0 jour de son contenu. De cette fa\u00e7on, nous \u00e9liminons toute forme de transmission de papier et <strong>nous contribuons \u00e9galement \u00e0 am\u00e9liorer nos ressources dans le cadre du plan de gestion durable de LAMA.<\/strong><\/p>\n<p>Le QR est int\u00e9gr\u00e9 \u00e0 l&rsquo;\u00e9tiquetage des produits, de sorte que toutes les informations figurent sur l\u2019\u00e9tiquette en elle-m\u00eame (que ce soit sous forme d&rsquo;autocollants ou de plaques).<\/p>\n<div id=\"attachment_4313\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4313\" class=\"size-medium wp-image-4313\" src=\"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-300x171.jpg\" alt=\"QR LAMA \" width=\"300\" height=\"171\" srcset=\"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-300x171.jpg 300w, https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-1024x585.jpg 1024w, https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-1536x878.jpg 1536w, https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-2048x1171.jpg 2048w, https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-345x198.jpg 345w, https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-screen-filters-700x400.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-4313\" class=\"wp-caption-text\">QR LAMA<\/p><\/div>\n<p>Dans cette m\u00eame ligne de compromis envers le num\u00e9rique et le caract\u00e8re imm\u00e9diat de l&rsquo;obtention des donn\u00e9es, Lama compte d\u2019une <strong>boutique en ligne\u00a0: <a href=\"http:\/\/www.lamastore.es\/\">www.lamastore.es<\/a><\/strong>, qui traite les commandes automatiquement sans besoin d&rsquo;imprimer sur papier. Nous sommes en train de travailler afin de rendre nos <strong><a href=\"https:\/\/www.lamastore.es\/es\/6-recambios-y-accesorios\">pi\u00e8ces de rechange et nos accessoires accessibles<\/a><\/strong> sous forme d\u2019un code QR pr\u00e9sent sur l&rsquo;\u00e9tiquette du produit.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Lama est une organization engag\u00e9e en faveur de l&rsquo;environnement et de l&rsquo;optimisation des ressources naturelles. Par cons\u00e9quent, nous avons suivi les exigences requises par le march\u00e9 actuel et nous\u00a0 r\u00e9pondons aux indications g\u00e9n\u00e9rales de la pand\u00e9mie ; tous nos produits portent les indications et&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4316,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-4325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tous"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LES CODES QR COMME ENGAGEMENT POUR L&#039;OPTIMISATION DES RESSOURCES | Lama<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LES CODES QR COMME ENGAGEMENT POUR L&#039;OPTIMISATION DES RESSOURCES | Lama\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Lama est une organization engag\u00e9e en faveur de l&rsquo;environnement et de l&rsquo;optimisation des ressources naturelles. Par cons\u00e9quent, nous avons suivi les exigences requises par le march\u00e9 actuel et nous\u00a0 r\u00e9pondons aux indications g\u00e9n\u00e9rales de la pand\u00e9mie ; tous nos produits portent les indications et...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/\" \/>\n<meta property=\"og:site_name\" content=\"LAMA Sistema de Filtrado\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-29T12:24:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T12:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2353\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lama\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lama\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/\"},\"author\":{\"name\":\"Lama\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\"},\"headline\":\"LES CODES QR COMME ENGAGEMENT POUR L&rsquo;OPTIMISATION DES RESSOURCES\",\"datePublished\":\"2021-03-29T12:24:59+00:00\",\"dateModified\":\"2021-03-29T12:25:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/\"},\"wordCount\":390,\"image\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/LAMA-sand-filters-scaled.jpg\",\"articleSection\":[\"Tous\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/\",\"url\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/\",\"name\":\"LES CODES QR COMME ENGAGEMENT POUR L'OPTIMISATION DES RESSOURCES | Lama\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/LAMA-sand-filters-scaled.jpg\",\"datePublished\":\"2021-03-29T12:24:59+00:00\",\"dateModified\":\"2021-03-29T12:25:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/LAMA-sand-filters-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/lama.es\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/LAMA-sand-filters-scaled.jpg\",\"width\":2560,\"height\":2353,\"caption\":\"LAMA-QR-sand-filters\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lama.es\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LES CODES QR COMME ENGAGEMENT POUR L&#8217;OPTIMISATION DES RESSOURCES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/lama.es\\\/fr\\\/\",\"name\":\"LAMA Sistema de Filtrado\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lama.es\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lama.es\\\/fr\\\/#\\\/schema\\\/person\\\/d100fcadbaca360b85e3e43ffb3f6638\",\"name\":\"Lama\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g\",\"caption\":\"Lama\"},\"sameAs\":[\"https:\\\/\\\/www.lama.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LES CODES QR COMME ENGAGEMENT POUR L'OPTIMISATION DES RESSOURCES | Lama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/","og_locale":"fr_FR","og_type":"article","og_title":"LES CODES QR COMME ENGAGEMENT POUR L'OPTIMISATION DES RESSOURCES | Lama","og_description":"&nbsp; Lama est une organization engag\u00e9e en faveur de l&rsquo;environnement et de l&rsquo;optimisation des ressources naturelles. Par cons\u00e9quent, nous avons suivi les exigences requises par le march\u00e9 actuel et nous\u00a0 r\u00e9pondons aux indications g\u00e9n\u00e9rales de la pand\u00e9mie ; tous nos produits portent les indications et...","og_url":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/","og_site_name":"LAMA Sistema de Filtrado","article_published_time":"2021-03-29T12:24:59+00:00","article_modified_time":"2021-03-29T12:25:33+00:00","og_image":[{"width":2560,"height":2353,"url":"http:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg","type":"image\/jpeg"}],"author":"Lama","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Lama","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#article","isPartOf":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/"},"author":{"name":"Lama","@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638"},"headline":"LES CODES QR COMME ENGAGEMENT POUR L&rsquo;OPTIMISATION DES RESSOURCES","datePublished":"2021-03-29T12:24:59+00:00","dateModified":"2021-03-29T12:25:33+00:00","mainEntityOfPage":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/"},"wordCount":390,"image":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#primaryimage"},"thumbnailUrl":"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg","articleSection":["Tous"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/","url":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/","name":"LES CODES QR COMME ENGAGEMENT POUR L'OPTIMISATION DES RESSOURCES | Lama","isPartOf":{"@id":"https:\/\/lama.es\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#primaryimage"},"image":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#primaryimage"},"thumbnailUrl":"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg","datePublished":"2021-03-29T12:24:59+00:00","dateModified":"2021-03-29T12:25:33+00:00","author":{"@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638"},"breadcrumb":{"@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#primaryimage","url":"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg","contentUrl":"https:\/\/lama.es\/wp-content\/uploads\/2021\/03\/LAMA-sand-filters-scaled.jpg","width":2560,"height":2353,"caption":"LAMA-QR-sand-filters"},{"@type":"BreadcrumbList","@id":"https:\/\/lama.es\/fr\/les-codes-qr-comme-engagement-pour-loptimisation-des-ressources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lama.es\/fr\/"},{"@type":"ListItem","position":2,"name":"LES CODES QR COMME ENGAGEMENT POUR L&#8217;OPTIMISATION DES RESSOURCES"}]},{"@type":"WebSite","@id":"https:\/\/lama.es\/fr\/#website","url":"https:\/\/lama.es\/fr\/","name":"LAMA Sistema de Filtrado","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lama.es\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/lama.es\/fr\/#\/schema\/person\/d100fcadbaca360b85e3e43ffb3f6638","name":"Lama","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/950796e1bd0975e59bb20ca14b398a263f38b1beaf3f11e685e2a12c209e1ec3?s=96&d=mm&r=g","caption":"Lama"},"sameAs":["https:\/\/www.lama.es"]}]}},"_links":{"self":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/4325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/comments?post=4325"}],"version-history":[{"count":5,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/4325\/revisions"}],"predecessor-version":[{"id":4330,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/posts\/4325\/revisions\/4330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/media\/4316"}],"wp:attachment":[{"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/media?parent=4325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/categories?post=4325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lama.es\/fr\/wp-json\/wp\/v2\/tags?post=4325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}